{"id":72004,"date":"2024-08-16T10:23:59","date_gmt":"2024-08-16T13:23:59","guid":{"rendered":"https:\/\/www.crossprensa.com.ar\/news\/?p=72004"},"modified":"2024-08-16T10:23:59","modified_gmt":"2024-08-16T13:23:59","slug":"mxgp-la-rossa-de-cairoli","status":"publish","type":"post","link":"https:\/\/www.crossprensa.com.ar\/news\/mxgp-la-rossa-de-cairoli\/mxgp\/","title":{"rendered":"MXGP: LA &#8220;ROSSA&#8221; DE CAIROLI."},"content":{"rendered":"<p>Lleg\u00f3 el momento esperado por todos. Por fin debuta la Ducati 450 Desmo!!! Y en manos de qui\u00e9n la desarroll\u00f3 y la pondr\u00e1 en carrera en el Mundial de Motocross: Aqu\u00ed te presentamos la Rossa (Roja en italiano) que llenar\u00e1 de ilusi\u00f3n a los espectadores y sobre todo a los italianos.<\/p>\n<p><!--more--><\/p>\n<p>Cairoli se va a enfrentar a los mejores de la actualidad, y con 39 a\u00f1os se les anima para correrles mano a mano&#8230; Veremos que sucede el Domingo, y como siempre van a tener todo en Crossprensa!!!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-72006\" src=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-scaled.jpeg 2560w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-300x200.jpeg 300w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-600x400.jpeg 600w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-768x512.jpeg 768w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-1536x1024.jpeg 1536w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-2048x1366.jpeg 2048w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H-FXQAEhH8i-1024x683.jpeg 1024w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-72007\" src=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-scaled.jpeg 2560w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-300x200.jpeg 300w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-600x400.jpeg 600w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-768x512.jpeg 768w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-1536x1024.jpeg 1536w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-2048x1366.jpeg 2048w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6IAnXgAAdiPb-1024x683.jpeg 1024w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-72008\" src=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-scaled.jpeg 2560w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-300x200.jpeg 300w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-600x400.jpeg 600w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-768x512.jpeg 768w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-1536x1024.jpeg 1536w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-2048x1366.jpeg 2048w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2024\/08\/GVF6H8CXAAAfmjK-1024x683.jpeg 1024w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lleg\u00f3 el momento esperado por todos. Por fin debuta la Ducati 450 Desmo!!! Y en&#8230;<\/p>\n","protected":false},"author":2,"featured_media":72005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-72004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mxgp"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/72004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/comments?post=72004"}],"version-history":[{"count":1,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/72004\/revisions"}],"predecessor-version":[{"id":72009,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/72004\/revisions\/72009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media\/72005"}],"wp:attachment":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media?parent=72004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/categories?post=72004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/tags?post=72004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}