{"id":67068,"date":"2023-11-29T11:57:40","date_gmt":"2023-11-29T14:57:40","guid":{"rendered":"https:\/\/www.crossprensa.com.ar\/news\/?p=67068"},"modified":"2023-11-29T12:05:06","modified_gmt":"2023-11-29T15:05:06","slug":"el-estado-de-salud-de-gonzalo-albert","status":"publish","type":"post","link":"https:\/\/www.crossprensa.com.ar\/news\/el-estado-de-salud-de-gonzalo-albert\/crossprensa\/","title":{"rendered":"EL ESTADO DE SALUD DE GONZALO ALBERT."},"content":{"rendered":"<p>La ca\u00edda fue fuerte y preocupante, aunque conoci\u00e9ndolo lo que mas le doli\u00f3 fue perder el campeonato. Las lesiones fueron varias, e inmediatamente fue trasladado para su atenci\u00f3n con un trabajo como siempre excelente de la cobertura m\u00e9dica del Campeonato Cordob\u00e9s.<\/p>\n<p><!--more--><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-67070\" src=\"http:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40.jpeg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40.jpeg 1600w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-300x200.jpeg 300w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-600x400.jpeg 600w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-768x512.jpeg 768w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-1536x1023.jpeg 1536w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-750x500.jpeg 750w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.53.40-1140x760.jpeg 1140w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/dsphoto22\/?hl=en\">Foto de Dami\u00e1n Saltiva.<\/a><\/p>\n<p>Un golpe que le sali\u00f3 barato&#8230; fractura de clav\u00edcula, fractura de costilla, y una mano en tres partes. Va a cirug\u00eda, estaba muy dolorido pero en este momento del Mi\u00e9rcoles (11:54), est\u00e1 entrando a quir\u00f3fano para recuperarse y volver a la moto lo antes posible.<\/p>\n<p>Gonzalo en comunicaci\u00f3n con nosotros, nos cont\u00f3 todo su agradecimiento a Mario Medina como presidente de Fecormot, a Leo Banner como promotor del campeonato, y a los m\u00e9dicos y cobertura por las atenciones recibidas y lo pronto que se resolvi\u00f3 todo para su atenci\u00f3n.<\/p>\n<p>Estaremos siguiendo su recuperaci\u00f3n como con todos los pilotos lesionados.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-67073\" src=\"http:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46.jpeg\" alt=\"\" width=\"1200\" height=\"1600\" srcset=\"https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46.jpeg 1200w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-225x300.jpeg 225w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-300x400.jpeg 300w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-768x1024.jpeg 768w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-1152x1536.jpeg 1152w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-750x1000.jpeg 750w, https:\/\/www.crossprensa.com.ar\/news\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-11.52.46-1140x1520.jpeg 1140w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ca\u00edda fue fuerte y preocupante, aunque conoci\u00e9ndolo lo que mas le doli\u00f3 fue perder&#8230;<\/p>\n","protected":false},"author":2,"featured_media":67069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[37,41],"tags":[],"class_list":["post-67068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crossprensa","category-mx-cordobes"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/67068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/comments?post=67068"}],"version-history":[{"count":3,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/67068\/revisions"}],"predecessor-version":[{"id":67074,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/67068\/revisions\/67074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media\/67069"}],"wp:attachment":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media?parent=67068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/categories?post=67068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/tags?post=67068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}