{"id":48063,"date":"2020-08-18T06:37:04","date_gmt":"2020-08-18T09:37:04","guid":{"rendered":"http:\/\/www.crossprensa.com.ar\/news\/?p=48063"},"modified":"2020-08-18T06:38:42","modified_gmt":"2020-08-18T09:38:42","slug":"tintin-vaca-brilla-en-espana","status":"publish","type":"post","link":"https:\/\/www.crossprensa.com.ar\/news\/tintin-vaca-brilla-en-espana\/hot-news\/","title":{"rendered":"TINTIN VACA BRILLA EN ESPA\u00d1A!"},"content":{"rendered":"<p>La perla del MX infantil argentino, llega con muchas ganas de aprender y evolucionar como piloto, una l\u00e1stima que su llegada coincida con esta \u00e9poca de cambios a nivel mundial a causa del\u00a0<strong>COV19<\/strong>, pero ya deja sus destellos en los entrenamientos que van realizando.<\/p>\n<p><!--more--><\/p>\n<p>Esto es un informe del equipo que ahora integra el piloto cordob\u00e9s al que vimos brillar en Argentina, ahora lo hace en la querida tierra espa\u00f1ola! La mejor suerte para \u00e9l y su familia en Europa&#8230; Desde Crossprensa estaremos siguiendo todo lo que haga!<\/p>\n<p>&#8220;Reci\u00e9n llegado de\u00a0<strong>Argentina<\/strong>, llega al\u00a0<strong>Team VDB<\/strong>\u00a0el piloto de 9 a\u00f1os,\u00a0<strong>Valent\u00edn<\/strong><strong>Vaca<\/strong>,\u00bbTin Tin 150\u2033 para disputar los campeonatos de\u00a0<strong>Catalunya<\/strong>\u00a0y\u00a0<strong>Espa\u00f1a<\/strong>\u00a0en las categorias de 50cc y 65cc.&#8221;<\/p>\n<p><strong>Tin Tin<\/strong>\u00a0volvi\u00f3 a la competici\u00f3n en la reanudaci\u00f3n del\u00a0<strong>Campeonato de Catalunya<\/strong>\u00a0que se disputaba en la localidad tarraconense de\u00a0<strong>Salom\u00f3<\/strong>, donde se alzaba con la victoria en la general en\u00a0<strong>MX50<\/strong>\u00a0tras conseguir una 2\u00aa y una 1\u00aa plaza en sus mangas.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-250179 lazyloaded\" src=\"https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o.jpg\" sizes=\"(max-width: 960px) 100vw, 960px\" srcset=\"https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o.jpg 960w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-300x300.jpg 300w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-150x150.jpg 150w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-768x768.jpg 768w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-265x265.jpg 265w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-504x504.jpg 504w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-100x100.jpg 100w\" alt=\"\" width=\"960\" height=\"960\" data-src=\"https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o.jpg\" data-srcset=\"https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o.jpg 960w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-300x300.jpg 300w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-150x150.jpg 150w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-768x768.jpg 768w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-265x265.jpg 265w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-504x504.jpg 504w, https:\/\/vdb.mx\/wp-content\/uploads\/2020\/08\/107927128_2118428171634358_6476004271089203416_o-100x100.jpg 100w\" \/><\/figure>\n<\/div>\n<p>Sin duda una manera inmejorable de empezar junto a nuestro equipo.<\/p>\n<p>Valent\u00edn cuenta con el respaldo del\u00a0<strong>Team VDB, Scorpion, Ethen; Gibson Tyres, Crossprensa Argentina y PHXtreme<\/strong>.<\/p>\n<p>Desde el equipo te deseamos muchis\u00edma suerte en esta aventura!!!&#8221;<\/p>\n<p>Y desde Crossprensa la mejor buena onda del mundo para toda la familia, y gracias a VDB por la confianza!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La perla del MX infantil argentino, llega con muchas ganas de aprender y evolucionar como&#8230;<\/p>\n","protected":false},"author":2,"featured_media":48067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[38,57],"tags":[],"class_list":["post-48063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hot-news","category-motocross"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/48063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/comments?post=48063"}],"version-history":[{"count":3,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/48063\/revisions"}],"predecessor-version":[{"id":48070,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/posts\/48063\/revisions\/48070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media\/48067"}],"wp:attachment":[{"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/media?parent=48063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/categories?post=48063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crossprensa.com.ar\/news\/wp-json\/wp\/v2\/tags?post=48063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}